{"id":6384,"date":"2026-04-14T12:21:31","date_gmt":"2026-04-14T12:21:31","guid":{"rendered":"https:\/\/reindesa.pre.interdigital.biz\/proyectos\/piscina-de-liner-convertida-a-lamina-armada\/"},"modified":"2026-04-16T08:36:34","modified_gmt":"2026-04-16T08:36:34","slug":"piscina-de-liner-convertida-a-lamina-armada","status":"publish","type":"proyectos","link":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/","title":{"rendered":"Piscina de liner convertida a l\u00e0mina armada"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":6566,"template":"","categoria_proyecto":[72],"etiqueta_proyecto":[],"class_list":["post-6384","proyectos","type-proyectos","status-publish","has-post-thumbnail","hentry","categoria_proyecto-piscines-a-mida"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piscina de liner convertida a l\u00e0mina armada | Projectes de piscines | Reindesa<\/title>\n<meta name=\"description\" content=\"Projecte de Reindesa: Piscina de liner convertida a l\u00e0mina armada. Construcci\u00f3, rehabilitaci\u00f3 o reforma de piscines amb solucions a mida, qualitat t\u00e8cnica i acabats professionals.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piscina de liner convertida a l\u00e0mina armada | Projectes de piscines | Reindesa\" \/>\n<meta property=\"og:description\" content=\"Projecte de Reindesa: Piscina de liner convertida a l\u00e0mina armada. Construcci\u00f3, rehabilitaci\u00f3 o reforma de piscines amb solucions a mida, qualitat t\u00e8cnica i acabats professionals.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/\" \/>\n<meta property=\"og:site_name\" content=\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T08:36:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2026\/04\/9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/\",\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/\",\"name\":\"Piscina de liner convertida a l\u00e0mina armada | Projectes de piscines | Reindesa\",\"isPartOf\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2026\/04\/9.jpg\",\"datePublished\":\"2026-04-14T12:21:31+00:00\",\"dateModified\":\"2026-04-16T08:36:34+00:00\",\"description\":\"Projecte de Reindesa: Piscina de liner convertida a l\u00e0mina armada. Construcci\u00f3, rehabilitaci\u00f3 o reforma de piscines amb solucions a mida, qualitat t\u00e8cnica i acabats professionals.\",\"breadcrumb\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#primaryimage\",\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2026\/04\/9.jpg\",\"contentUrl\":\"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2026\/04\/9.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Piscina de liner convertida a l\u00e0mina armada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website\",\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/\",\"name\":\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\",\"description\":\"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piscina de liner convertida a l\u00e0mina armada | Projectes de piscines | Reindesa","description":"Projecte de Reindesa: Piscina de liner convertida a l\u00e0mina armada. Construcci\u00f3, rehabilitaci\u00f3 o reforma de piscines amb solucions a mida, qualitat t\u00e8cnica i acabats professionals.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/","og_locale":"ca_ES","og_type":"article","og_title":"Piscina de liner convertida a l\u00e0mina armada | Projectes de piscines | Reindesa","og_description":"Projecte de Reindesa: Piscina de liner convertida a l\u00e0mina armada. Construcci\u00f3, rehabilitaci\u00f3 o reforma de piscines amb solucions a mida, qualitat t\u00e8cnica i acabats professionals.","og_url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/","og_site_name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","article_modified_time":"2026-04-16T08:36:34+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2026\/04\/9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/","url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/","name":"Piscina de liner convertida a l\u00e0mina armada | Projectes de piscines | Reindesa","isPartOf":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#primaryimage"},"image":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#primaryimage"},"thumbnailUrl":"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2026\/04\/9.jpg","datePublished":"2026-04-14T12:21:31+00:00","dateModified":"2026-04-16T08:36:34+00:00","description":"Projecte de Reindesa: Piscina de liner convertida a l\u00e0mina armada. Construcci\u00f3, rehabilitaci\u00f3 o reforma de piscines amb solucions a mida, qualitat t\u00e8cnica i acabats professionals.","breadcrumb":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#primaryimage","url":"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2026\/04\/9.jpg","contentUrl":"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2026\/04\/9.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/piscina-de-liner-convertida-a-lamina-armada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/projectes\/"},{"@type":"ListItem","position":3,"name":"Piscina de liner convertida a l\u00e0mina armada"}]},{"@type":"WebSite","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website","url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/","name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","description":"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/proyectos\/6384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/proyectos"}],"about":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/types\/proyectos"}],"version-history":[{"count":1,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/proyectos\/6384\/revisions"}],"predecessor-version":[{"id":6573,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/proyectos\/6384\/revisions\/6573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/media\/6566"}],"wp:attachment":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/media?parent=6384"}],"wp:term":[{"taxonomy":"categoria_proyecto","embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/categoria_proyecto?post=6384"},{"taxonomy":"etiqueta_proyecto","embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/etiqueta_proyecto?post=6384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}