{"id":5791,"date":"2015-02-24T19:02:34","date_gmt":"2015-02-24T19:02:34","guid":{"rendered":"https:\/\/reindesa.pre.interdigital.biz\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/"},"modified":"2015-02-24T19:02:34","modified_gmt":"2015-02-24T19:02:34","slug":"les-piscines-del-futur-connectades-a-internet-fluidra-connect","status":"publish","type":"post","link":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/","title":{"rendered":"Les piscines del futur, connectades a Internet. Fluidra Connect."},"content":{"rendered":"<p>A dia d&#8217;avui, s\u00f3n pocs els que no disposen de connexi\u00f3 a internet, ja sigui a casa, a la feina, al m\u00f2bil\u2026 Estar connectats ha passat a ser una cosa comuna, que ens facilita la vida en molts aspectes de les nostres tasques di\u00e0ries. I \u00e9s precisament gr\u00e0cies a la tecnologia existent ia la familiaritzaci\u00f3 dels usuaris amb ella, que <a title=\"Fluidra\" href=\"http:\/\/www.fluidra.com\" target=\"_blank\">Fluidra<\/a> ha creat <a title=\"Fluidra Connect\" href=\"\/www.fluidraconnect.com\" target=\"_blank\">Fluidra Connect<\/a> .   <a href=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-1845\" alt=\"fluidra_connect_home01_footer\" src=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg\" width=\"1360\" height=\"242\" srcset=\"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg 1360w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer-300x53.jpg 300w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer-1024x182.jpg 1024w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer-768x137.jpg 768w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer-600x107.jpg 600w\" sizes=\"(max-width: 1360px) 100vw, 1360px\" \/><\/a><\/p>\n<p>No nom\u00e9s \u00e9s dom\u00f2tica aplicada a la piscina, sin\u00f3 Internet aplicat a la piscina.  <strong>El control de la piscina, amb tota la informaci\u00f3, des de qualsevol lloc i en qualsevol moment.  <\/strong>La pedra angular del projecte \u00e9s Connect Box, el centre d&#8217;operacions que permet controlar els diferents productes.  <strong>Si hi ha algun problema amb la teva piscina, ho sabrem i corregirem remotament sense que hagis de moure ni un sol dit.<\/strong>  No \u00e9s genial?<\/p>\n<p>Descobreix en aquest v\u00eddeo algunes de les caracter\u00edstiques sorprenents d&#8217;aquesta nova era de piscines:<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/8opSfzcHle0\" height=\"315\" width=\"560\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h1><span style=\"text-decoration: underline;\"><span style=\"background-color: #ffffff;\"><b>Reindesa. Una de les cinc empreses catalanes<\/b> <em id=\"__mceDel\"><b>seleccionades per fer i provar el projecte.<\/b><\/em><\/span><\/span><\/h1>\n<p>Des de Reindesa estem molt orgullosos d&#8217;anunciar que hem <strong>estat una de les cinc empreses catalanes seleccionades per dur a terme aquest projecte<\/strong> . D&#8217;aquesta manera, es podr\u00e0 comen\u00e7ar amb els assaigs i diferents anelles dels testeigs. <\/p>\n<p><b>La revoluci\u00f3 de la piscina est\u00e0 en fase de desenvolupament, per\u00f2<\/b> <strong>ben aviat ser\u00e0 una realitat<\/strong> . Des del sistema de filtraci\u00f3 a la il\u00b7luminaci\u00f3, passant per la climatitzaci\u00f3 o tractament qu\u00edmic de l&#8217;aigua, tots els equips que fan possible el funcionament de la piscina en condicions \u00f2ptimes podran ser controlats amb un dispositiu m\u00f2bil. <\/p>\n<p><a title=\"Fluidra Connect\" href=\"http:\/\/www.fluidraconnect.com\" target=\"_blank\"><b><i><span style=\"text-decoration: underline;\">Fluidra Connect<\/span><\/i><\/b><\/a> arriba per fer-te la vida m\u00e9s f\u00e0cil, i des de <strong>Reindesa volem ser plenament part\u00edcips del teu benestar<\/strong> . Treballem perqu\u00e8 en un futur, no gaire lluny\u00e0, tu nom\u00e9s hagis de preocupar-te per gaudir de la teva piscina. <\/p>\n<p><a href=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_comofunciona.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-1846\" alt=\"fluidra_connect_como_funciona\" src=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_comofunciona.jpg\" width=\"788\" height=\"805\" srcset=\"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2015\/02\/fluidra_connect_comofunciona.jpg 788w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2015\/02\/fluidra_connect_comofunciona-294x300.jpg 294w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2015\/02\/fluidra_connect_comofunciona-768x785.jpg 768w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2015\/02\/fluidra_connect_comofunciona-600x613.jpg 600w\" sizes=\"(max-width: 788px) 100vw, 788px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A dia d&#8217;avui, s\u00f3n pocs els que no disposen de connexi\u00f3 a internet, ja sigui a casa, a la feina, al m\u00f2bil\u2026 Estar connectats ha passat a ser una cosa comuna, que ens facilita la vida en molts aspectes de les nostres tasques di\u00e0ries. I \u00e9s precisament gr\u00e0cies a la tecnologia existent ia la familiaritzaci\u00f3 dels usuaris amb ella, que Fluidra ha creat Fluidra Connect . No nom\u00e9s \u00e9s dom\u00f2tica aplicada a la piscina, sin\u00f3 Internet aplicat a la piscina. El control de la piscina, amb tota la informaci\u00f3, des de qualsevol lloc i en qualsevol moment. La pedra angular del projecte \u00e9s Connect Box, el centre d&#8217;operacions que permet controlar els diferents productes. Si hi ha algun problema amb la teva piscina, ho sabrem i corregirem remotament sense que hagis de moure ni un sol dit. No \u00e9s genial? Descobreix en aquest v\u00eddeo algunes de les caracter\u00edstiques sorprenents d&#8217;aquesta nova era de piscines: &nbsp; Reindesa. Una de les cinc empreses catalanes seleccionades per fer i provar el projecte. Des de Reindesa estem molt orgullosos d&#8217;anunciar que hem estat una de les cinc empreses catalanes seleccionades per dur a terme aquest projecte . D&#8217;aquesta manera, es podr\u00e0 comen\u00e7ar amb els assaigs i diferents anelles dels testeigs. La revoluci\u00f3 de la piscina est\u00e0 en fase de desenvolupament, per\u00f2 ben aviat ser\u00e0 una realitat . Des del sistema de filtraci\u00f3 a la il\u00b7luminaci\u00f3, passant per la climatitzaci\u00f3 o tractament qu\u00edmic de l&#8217;aigua, tots els equips que fan possible el funcionament de la piscina en condicions \u00f2ptimes podran ser controlats amb un dispositiu m\u00f2bil. Fluidra Connect arriba per fer-te la vida m\u00e9s f\u00e0cil, i des de Reindesa volem ser plenament part\u00edcips del teu benestar . Treballem perqu\u00e8 en un futur, no gaire lluny\u00e0, tu nom\u00e9s hagis de preocupar-te per gaudir de la teva piscina. &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[731,970,971,972],"class_list":["post-5791","post","type-post","status-publish","format-standard","hentry","category-el-tecnic-de-la-piscina","tag-fluidra","tag-fluidra-connect","tag-internet-of-pools","tag-piscines-del-futur"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les piscines del futur, connectades a Internet. Fluidra Connect.<\/title>\n<meta name=\"description\" content=\"Reindesa forma part de Fluidra Connect, un futur molt proper on les piscines estaran connectades a la xarxa. I on tu nom\u00e9s haur\u00e0s de gaudir-ne\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les piscines del futur, connectades a Internet. Fluidra Connect.\" \/>\n<meta property=\"og:description\" content=\"Reindesa forma part de Fluidra Connect, un futur molt proper on les piscines estaran connectades a la xarxa. I on tu nom\u00e9s haur\u00e0s de gaudir-ne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/\" \/>\n<meta property=\"og:site_name\" content=\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-24T19:02:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg\" \/>\n<meta name=\"author\" content=\"El t\u00e9cnico de Reindesa Piscines\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"El t\u00e9cnico de Reindesa Piscines\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/\"},\"author\":{\"name\":\"El t\u00e9cnico de Reindesa Piscines\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15a90efbc239f4ad18e1ee391f89c722\"},\"headline\":\"Les piscines del futur, connectades a Internet. Fluidra Connect.\",\"datePublished\":\"2015-02-24T19:02:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/\"},\"wordCount\":329,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg\",\"keywords\":[\"fluidra\",\"Fluidra Connect\",\"Internet of pools\",\"piscines del futur\"],\"articleSection\":[\"El t\u00e8cnic de la piscina\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/\",\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/\",\"name\":\"Les piscines del futur, connectades a Internet. Fluidra Connect.\",\"isPartOf\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg\",\"datePublished\":\"2015-02-24T19:02:34+00:00\",\"author\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15a90efbc239f4ad18e1ee391f89c722\"},\"description\":\"Reindesa forma part de Fluidra Connect, un futur molt proper on les piscines estaran connectades a la xarxa. I on tu nom\u00e9s haur\u00e0s de gaudir-ne\",\"breadcrumb\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#primaryimage\",\"url\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg\",\"contentUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les piscines del futur, connectades a Internet. Fluidra Connect.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website\",\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/\",\"name\":\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\",\"description\":\"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15a90efbc239f4ad18e1ee391f89c722\",\"name\":\"El t\u00e9cnico de Reindesa Piscines\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/3bc13d45ae0889ca10a879ed37cd4ad0b0ab81a3e83ce9d8d36e3c83e2eeabd7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3bc13d45ae0889ca10a879ed37cd4ad0b0ab81a3e83ce9d8d36e3c83e2eeabd7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3bc13d45ae0889ca10a879ed37cd4ad0b0ab81a3e83ce9d8d36e3c83e2eeabd7?s=96&d=mm&r=g\",\"caption\":\"El t\u00e9cnico de Reindesa Piscines\"},\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/author\/tecnico\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les piscines del futur, connectades a Internet. Fluidra Connect.","description":"Reindesa forma part de Fluidra Connect, un futur molt proper on les piscines estaran connectades a la xarxa. I on tu nom\u00e9s haur\u00e0s de gaudir-ne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/","og_locale":"ca_ES","og_type":"article","og_title":"Les piscines del futur, connectades a Internet. Fluidra Connect.","og_description":"Reindesa forma part de Fluidra Connect, un futur molt proper on les piscines estaran connectades a la xarxa. I on tu nom\u00e9s haur\u00e0s de gaudir-ne","og_url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/","og_site_name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","article_published_time":"2015-02-24T19:02:34+00:00","og_image":[{"url":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg","type":"","width":"","height":""}],"author":"El t\u00e9cnico de Reindesa Piscines","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"El t\u00e9cnico de Reindesa Piscines","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#article","isPartOf":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/"},"author":{"name":"El t\u00e9cnico de Reindesa Piscines","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15a90efbc239f4ad18e1ee391f89c722"},"headline":"Les piscines del futur, connectades a Internet. Fluidra Connect.","datePublished":"2015-02-24T19:02:34+00:00","mainEntityOfPage":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/"},"wordCount":329,"commentCount":0,"image":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#primaryimage"},"thumbnailUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg","keywords":["fluidra","Fluidra Connect","Internet of pools","piscines del futur"],"articleSection":["El t\u00e8cnic de la piscina"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/","url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/","name":"Les piscines del futur, connectades a Internet. Fluidra Connect.","isPartOf":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#primaryimage"},"image":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#primaryimage"},"thumbnailUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg","datePublished":"2015-02-24T19:02:34+00:00","author":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15a90efbc239f4ad18e1ee391f89c722"},"description":"Reindesa forma part de Fluidra Connect, un futur molt proper on les piscines estaran connectades a la xarxa. I on tu nom\u00e9s haur\u00e0s de gaudir-ne","breadcrumb":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#primaryimage","url":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg","contentUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2015\/02\/fluidra_connect_home01_footer.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/les-piscines-del-futur-connectades-a-internet-fluidra-connect\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/"},{"@type":"ListItem","position":2,"name":"Les piscines del futur, connectades a Internet. Fluidra Connect."}]},{"@type":"WebSite","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website","url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/","name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","description":"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15a90efbc239f4ad18e1ee391f89c722","name":"El t\u00e9cnico de Reindesa Piscines","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/3bc13d45ae0889ca10a879ed37cd4ad0b0ab81a3e83ce9d8d36e3c83e2eeabd7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3bc13d45ae0889ca10a879ed37cd4ad0b0ab81a3e83ce9d8d36e3c83e2eeabd7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3bc13d45ae0889ca10a879ed37cd4ad0b0ab81a3e83ce9d8d36e3c83e2eeabd7?s=96&d=mm&r=g","caption":"El t\u00e9cnico de Reindesa Piscines"},"url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/author\/tecnico\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts\/5791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/comments?post=5791"}],"version-history":[{"count":0,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts\/5791\/revisions"}],"wp:attachment":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/media?parent=5791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/categories?post=5791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/tags?post=5791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}