{"id":5665,"date":"2012-12-17T12:00:19","date_gmt":"2012-12-17T12:00:19","guid":{"rendered":"https:\/\/reindesa.pre.interdigital.biz\/no-saps-que-demanar-als-reis-mags\/"},"modified":"2012-12-17T12:00:19","modified_gmt":"2012-12-17T12:00:19","slug":"no-saps-que-demanar-als-reis-mags","status":"publish","type":"post","link":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/","title":{"rendered":"No saps qu\u00e8 demanar als reis mags?"},"content":{"rendered":"<p><strong>A <a href=\"http:\/\/reindesa.com\/\" target=\"_blank\">Reindesa<\/a> et donem molt\u00edssimes idees!<\/strong><\/p>\n<p> Aprofita les nostres <strong>ofertes<\/strong> i sorpr\u00e8n els teus.<\/p>\n<p><a href=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1352\" title=\"feliznavitat2012\" src=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg\" alt=\"\" width=\"736\" height=\"1369\" srcset=\"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg 736w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2012\/12\/feliznavidad2012-161x300.jpg 161w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2012\/12\/feliznavidad2012-551x1024.jpg 551w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2012\/12\/feliznavidad2012-600x1116.jpg 600w\" sizes=\"(max-width: 736px) 100vw, 736px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Reindesa et donem molt\u00edssimes idees! Aprofita les nostres ofertes i sorpr\u00e8n els teus.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[464],"tags":[],"class_list":["post-5665","post","type-post","status-publish","format-standard","hentry","category-piscines-sempre-a-punt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No saps qu\u00e8 demanar als reis mags? | Blog de piscines | Reindesa<\/title>\n<meta name=\"description\" content=\"No saps qu\u00e8 demanar als reis mags?. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No saps qu\u00e8 demanar als reis mags? | Blog de piscines | Reindesa\" \/>\n<meta property=\"og:description\" content=\"No saps qu\u00e8 demanar als reis mags?. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/\" \/>\n<meta property=\"og:site_name\" content=\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-17T12:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg\" \/>\n<meta name=\"author\" content=\"Reindesa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reindesa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/\"},\"author\":{\"name\":\"Reindesa\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5\"},\"headline\":\"No saps qu\u00e8 demanar als reis mags?\",\"datePublished\":\"2012-12-17T12:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/\"},\"wordCount\":23,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg\",\"articleSection\":[\"Piscines Sempre a Punt\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/\",\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/\",\"name\":\"No saps qu\u00e8 demanar als reis mags? | Blog de piscines | Reindesa\",\"isPartOf\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg\",\"datePublished\":\"2012-12-17T12:00:19+00:00\",\"author\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5\"},\"description\":\"No saps qu\u00e8 demanar als reis mags?. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.\",\"breadcrumb\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#primaryimage\",\"url\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg\",\"contentUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No saps qu\u00e8 demanar als reis mags?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website\",\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/\",\"name\":\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\",\"description\":\"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5\",\"name\":\"Reindesa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g\",\"caption\":\"Reindesa\"},\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/author\/reindesa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No saps qu\u00e8 demanar als reis mags? | Blog de piscines | Reindesa","description":"No saps qu\u00e8 demanar als reis mags?. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/","og_locale":"ca_ES","og_type":"article","og_title":"No saps qu\u00e8 demanar als reis mags? | Blog de piscines | Reindesa","og_description":"No saps qu\u00e8 demanar als reis mags?. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.","og_url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/","og_site_name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","article_published_time":"2012-12-17T12:00:19+00:00","og_image":[{"url":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg","type":"","width":"","height":""}],"author":"Reindesa","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Reindesa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#article","isPartOf":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/"},"author":{"name":"Reindesa","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5"},"headline":"No saps qu\u00e8 demanar als reis mags?","datePublished":"2012-12-17T12:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/"},"wordCount":23,"commentCount":0,"image":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#primaryimage"},"thumbnailUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg","articleSection":["Piscines Sempre a Punt"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/","url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/","name":"No saps qu\u00e8 demanar als reis mags? | Blog de piscines | Reindesa","isPartOf":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#primaryimage"},"image":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#primaryimage"},"thumbnailUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg","datePublished":"2012-12-17T12:00:19+00:00","author":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5"},"description":"No saps qu\u00e8 demanar als reis mags?. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.","breadcrumb":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#primaryimage","url":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg","contentUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2012\/12\/feliznavidad2012.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/no-saps-que-demanar-als-reis-mags\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/"},{"@type":"ListItem","position":2,"name":"No saps qu\u00e8 demanar als reis mags?"}]},{"@type":"WebSite","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website","url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/","name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","description":"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5","name":"Reindesa","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g","caption":"Reindesa"},"url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/author\/reindesa\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts\/5665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/comments?post=5665"}],"version-history":[{"count":0,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts\/5665\/revisions"}],"wp:attachment":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/media?parent=5665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/categories?post=5665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/tags?post=5665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}