{"id":5510,"date":"2011-08-30T12:56:49","date_gmt":"2011-08-30T12:56:49","guid":{"rendered":"https:\/\/reindesa.pre.interdigital.biz\/waterworld-a-la-xina\/"},"modified":"2011-08-30T12:56:49","modified_gmt":"2011-08-30T12:56:49","slug":"waterworld-a-la-xina","status":"publish","type":"post","link":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/","title":{"rendered":"WATERWORLD a la Xina"},"content":{"rendered":"<p>Seguim amb la nostra recopilaci\u00f3 de <a href=\"http:\/\/www.reindesa.com\/blog\/category\/piscinas-imposibles\/\">piscines impossibles<\/a> amb aquest espectacular projecte guanyador d&#8217;un concurs internacional de disseny del <a href=\"http:\/\/www.atkins-me.com\/\">Grup Atkins<\/a> . Situat en una pedrera de Songjiang, Xina, l&#8217;hotel incrustat en una pedrera plena d&#8217;aigua est\u00e0 constru\u00eft tenint en compte els elements naturals que us envolten i adaptant-se a la perfecci\u00f3. Amb 400 habitacions i amb la peculiaritat sorprenent de la ubicaci\u00f3 d&#8217;alguna d&#8217;elles sota l&#8217;aigua.  <\/p>\n<p><a href=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-533\" title=\"waterworld1\" src=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg\" alt=\"waterworld1\" width=\"640\" height=\"333\" srcset=\"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2011\/08\/waterworld1.jpg 640w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2011\/08\/waterworld1-300x156.jpg 300w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2011\/08\/waterworld1-600x312.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>A la seva \u00e0rea a la vora de l&#8217;aigua t\u00e9 una piscina de luxe i un centre per a esports extrems com escalada lliure i salt amb bungee que est\u00e0 constru\u00eft sobre el planter i es pot accedir amb ascensors que pugen des de l&#8217;aigua.<\/p>\n<p><a href=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld21.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-535\" title=\"waterworld2\" src=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld21.jpg\" alt=\"waterworld2\" width=\"640\" height=\"495\" srcset=\"https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2011\/08\/waterworld21.jpg 640w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2011\/08\/waterworld21-300x232.jpg 300w, https:\/\/reindesa2.pre.interdigital.biz\/wp-content\/uploads\/2011\/08\/waterworld21-600x464.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>via <a href=\"http:\/\/www.thecoolhunter.com.au\/architecture\/WATERWORLD---China\/\">The cool hunter<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seguim amb la nostra recopilaci\u00f3 de piscines impossibles amb aquest espectacular projecte guanyador d&#8217;un concurs internacional de disseny del Grup Atkins . Situat en una pedrera de Songjiang, Xina, l&#8217;hotel incrustat en una pedrera plena d&#8217;aigua est\u00e0 constru\u00eft tenint en compte els elements naturals que us envolten i adaptant-se a la perfecci\u00f3. Amb 400 habitacions i amb la peculiaritat sorprenent de la ubicaci\u00f3 d&#8217;alguna d&#8217;elles sota l&#8217;aigua. A la seva \u00e0rea a la vora de l&#8217;aigua t\u00e9 una piscina de luxe i un centre per a esports extrems com escalada lliure i salt amb bungee que est\u00e0 constru\u00eft sobre el planter i es pot accedir amb ascensors que pugen des de l&#8217;aigua. via The cool hunter<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[],"class_list":["post-5510","post","type-post","status-publish","format-standard","hentry","category-la-teva-piscina-ideal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WATERWORLD a la Xina | Blog de piscines | Reindesa<\/title>\n<meta name=\"description\" content=\"WATERWORLD a la Xina. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WATERWORLD a la Xina | Blog de piscines | Reindesa\" \/>\n<meta property=\"og:description\" content=\"WATERWORLD a la Xina. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/\" \/>\n<meta property=\"og:site_name\" content=\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-30T12:56:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg\" \/>\n<meta name=\"author\" content=\"Reindesa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reindesa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/\"},\"author\":{\"name\":\"Reindesa\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5\"},\"headline\":\"WATERWORLD a la Xina\",\"datePublished\":\"2011-08-30T12:56:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/\"},\"wordCount\":128,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg\",\"articleSection\":[\"La teva Piscina Ideal\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/\",\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/\",\"name\":\"WATERWORLD a la Xina | Blog de piscines | Reindesa\",\"isPartOf\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg\",\"datePublished\":\"2011-08-30T12:56:49+00:00\",\"author\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5\"},\"description\":\"WATERWORLD a la Xina. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.\",\"breadcrumb\":{\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#primaryimage\",\"url\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg\",\"contentUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WATERWORLD a la Xina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website\",\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/\",\"name\":\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\",\"description\":\"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5\",\"name\":\"Reindesa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g\",\"caption\":\"Reindesa\"},\"url\":\"https:\/\/reindesa2.pre.interdigital.biz\/ca\/author\/reindesa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WATERWORLD a la Xina | Blog de piscines | Reindesa","description":"WATERWORLD a la Xina. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/","og_locale":"ca_ES","og_type":"article","og_title":"WATERWORLD a la Xina | Blog de piscines | Reindesa","og_description":"WATERWORLD a la Xina. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.","og_url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/","og_site_name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","article_published_time":"2011-08-30T12:56:49+00:00","og_image":[{"url":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg","type":"","width":"","height":""}],"author":"Reindesa","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Reindesa","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#article","isPartOf":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/"},"author":{"name":"Reindesa","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5"},"headline":"WATERWORLD a la Xina","datePublished":"2011-08-30T12:56:49+00:00","mainEntityOfPage":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/"},"wordCount":128,"commentCount":0,"image":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#primaryimage"},"thumbnailUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg","articleSection":["La teva Piscina Ideal"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/","url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/","name":"WATERWORLD a la Xina | Blog de piscines | Reindesa","isPartOf":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#primaryimage"},"image":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#primaryimage"},"thumbnailUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg","datePublished":"2011-08-30T12:56:49+00:00","author":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5"},"description":"WATERWORLD a la Xina. Article del blog de Reindesa amb consells, informaci\u00f3 i solucions sobre construcci\u00f3, manteniment i rehabilitaci\u00f3 de piscines.","breadcrumb":{"@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#primaryimage","url":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg","contentUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/08\/waterworld1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/waterworld-a-la-xina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/"},{"@type":"ListItem","position":2,"name":"WATERWORLD a la Xina"}]},{"@type":"WebSite","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#website","url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/","name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","description":"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5","name":"Reindesa","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g","caption":"Reindesa"},"url":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/author\/reindesa\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts\/5510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/comments?post=5510"}],"version-history":[{"count":0,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts\/5510\/revisions"}],"wp:attachment":[{"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/media?parent=5510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/categories?post=5510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reindesa2.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/tags?post=5510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}